{"id":6733,"date":"2024-07-24T13:51:22","date_gmt":"2024-07-24T10:51:22","guid":{"rendered":"https:\/\/haberkuzey.com\/index.php\/2024\/07\/24\/nehir-oyunu-portekizde-sahnelendi\/"},"modified":"2024-07-24T13:51:22","modified_gmt":"2024-07-24T10:51:22","slug":"nehir-oyunu-portekizde-sahnelendi","status":"publish","type":"post","link":"https:\/\/haberkuzey.com\/index.php\/2024\/07\/24\/nehir-oyunu-portekizde-sahnelendi\/","title":{"rendered":"\u2018Nehir\u2019 oyunu Portekiz\u2019de sahnelendi"},"content":{"rendered":"<div>\n<div class=\"mariselle-image-container center\">\n                                            <\/div>\n<p>Girne Tiyatro Su ve Roi Tiyatrosu\u2019nun ortak projesi \u2018Nehir\u2019 oyunu, Portekiz\u2019de d\u00fczenlenen 3. MIT24 Uluslararas\u0131 Tiyatro Festivali\u2019nde sahne ald\u0131. Yap\u0131lan a\u00e7\u0131klamaya g\u00f6re, 18 Temmuz\u2019da Portekiz\u2019in merkezinde bulunan Circus Tiyatro\u2019da g\u00f6sterilen oyunu, festival organizasyon ba\u015fkan\u0131 Rui Madera, Avrasya Tiyatrolar Birli\u011fi Ba\u015fkan\u0131 Aleksandr Kiniga, Avrasya Tiyatrolar Birli\u011fi Genel Sekreteri Kubilay Erdelikara, festivale kat\u0131lan 8 \u00fclkenin t\u00fcm oyuncular\u0131 ve Avrasya Tiyatrolar Birli\u011fi\u2019nin 28 \u00fclke temsilcisi de izledi.<\/p>\n<p>Andreas Nicolaidis taraf\u0131ndan yaz\u0131lan ve Derman Atik taraf\u0131ndan T\u00fcrk\u00e7e, Rumca ve \u0130ngilizce olmak \u00fczere \u00fc\u00e7 dilde sahnelenen \u2018Nehir\u2019 oyununda ayr\u0131ca Portekizce altyaz\u0131 kullan\u0131ld\u0131.<\/p>\n<p>Girne Tiyatro Su oyuncusu Cenk G\u00fcr\u00e7a\u011f, Tiyatro Roi oyuncular\u0131 Valentina Sofokleus ve oyunun yazar\u0131 Andreas Nicolaidis\u2019in rol ald\u0131\u011f\u0131 oyunun, reji asistanl\u0131\u011f\u0131n\u0131 Girne Tiyatro Su oyuncusu \u0130lk\u015fen Varo\u011flu Atik, \u0131\u015f\u0131k tasar\u0131m ve uygulamas\u0131n\u0131 Tiyatro Roi\u2019den Dimitris Giannakis \u00fcstlendi. Oyundaki altyaz\u0131lar\u0131 ise Girne Tiyatro Su oyuncusu \u0130lde Atik uygulad\u0131.<\/p>\n<p>Ekip, K\u0131br\u0131s\u2019a d\u00f6nd\u00fc\u011f\u00fcnde oyun, ilk program dahilinde PEO Sendikas\u0131\u2019n\u0131n amfi tiyatrosunda 9 A\u011fustos 2024 tarihinde ve Lefko\u015fa \u00dcniversitesi\u2019nde 18 Eyl\u00fcl 2024\u2019te sahnelenecek.<\/p>\n<\/p><\/div>\n<p><script async\n                    defer\n                    crossorigin=\"anonymous\"\n                    src=\"https:\/\/connect.facebook.net\/tr_TR\/sdk.js#xfbml=1&#038;version=v3.3\"\n            ><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Girne Tiyatro Su ve Roi Tiyatrosu\u2019nun ortak projesi \u2018Nehir\u2019 oyunu, Portekiz\u2019de d\u00fczenlenen 3. MIT24 Uluslararas\u0131 Tiyatro Festivali\u2019nde sahne ald\u0131. Yap\u0131lan a\u00e7\u0131klamaya g\u00f6re, 18 Temmuz\u2019da Portekiz\u2019in merkezinde bulunan Circus Tiyatro\u2019da g\u00f6sterilen oyunu, festival organizasyon ba\u015fkan\u0131 Rui Madera, Avrasya Tiyatrolar Birli\u011fi Ba\u015fkan\u0131 Aleksandr Kiniga, Avrasya Tiyatrolar Birli\u011fi Genel Sekreteri Kubilay Erdelikara, festivale kat\u0131lan 8 \u00fclkenin t\u00fcm oyuncular\u0131 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6734,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"footnotes":""},"categories":[5],"tags":[],"class_list":["post-6733","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-turkiye"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u2018Nehir\u2019 oyunu Portekiz\u2019de sahnelendi - Haber Kuzey<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/haberkuzey.com\/index.php\/2024\/07\/24\/nehir-oyunu-portekizde-sahnelendi\/\" \/>\n<meta property=\"og:locale\" content=\"tr_TR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u2018Nehir\u2019 oyunu Portekiz\u2019de sahnelendi - Haber Kuzey\" \/>\n<meta property=\"og:description\" content=\"Girne Tiyatro Su ve Roi Tiyatrosu\u2019nun ortak projesi \u2018Nehir\u2019 oyunu, Portekiz\u2019de d\u00fczenlenen 3. MIT24 Uluslararas\u0131 Tiyatro Festivali\u2019nde sahne ald\u0131. Yap\u0131lan a\u00e7\u0131klamaya g\u00f6re, 18 Temmuz\u2019da Portekiz\u2019in merkezinde bulunan Circus Tiyatro\u2019da g\u00f6sterilen oyunu, festival organizasyon ba\u015fkan\u0131 Rui Madera, Avrasya Tiyatrolar Birli\u011fi Ba\u015fkan\u0131 Aleksandr Kiniga, Avrasya Tiyatrolar Birli\u011fi Genel Sekreteri Kubilay Erdelikara, festivale kat\u0131lan 8 \u00fclkenin t\u00fcm oyuncular\u0131 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/haberkuzey.com\/index.php\/2024\/07\/24\/nehir-oyunu-portekizde-sahnelendi\/\" \/>\n<meta property=\"og:site_name\" content=\"Haber Kuzey\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-24T10:51:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/brtk.net\/wp-content\/uploads\/2024\/07\/24\/546464.jpg?ver=f65757258300f06cea0870e7644ea498\" \/>\n<meta name=\"author\" content=\"haberkuzey\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Yazan:\" \/>\n\t<meta name=\"twitter:data1\" content=\"haberkuzey\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tahmini okuma s\u00fcresi\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 dakika\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/haberkuzey.com\\\/index.php\\\/2024\\\/07\\\/24\\\/nehir-oyunu-portekizde-sahnelendi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/haberkuzey.com\\\/index.php\\\/2024\\\/07\\\/24\\\/nehir-oyunu-portekizde-sahnelendi\\\/\"},\"author\":{\"name\":\"haberkuzey\",\"@id\":\"https:\\\/\\\/haberkuzey.com\\\/#\\\/schema\\\/person\\\/3372109ec735f9333f4fa47ebb9605ca\"},\"headline\":\"\u2018Nehir\u2019 oyunu Portekiz\u2019de sahnelendi\",\"datePublished\":\"2024-07-24T10:51:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/haberkuzey.com\\\/index.php\\\/2024\\\/07\\\/24\\\/nehir-oyunu-portekizde-sahnelendi\\\/\"},\"wordCount\":200,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/haberkuzey.com\\\/index.php\\\/2024\\\/07\\\/24\\\/nehir-oyunu-portekizde-sahnelendi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/haberkuzey.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/546464.jpg\",\"articleSection\":[\"T\u00fcrkiye\"],\"inLanguage\":\"tr\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/haberkuzey.com\\\/index.php\\\/2024\\\/07\\\/24\\\/nehir-oyunu-portekizde-sahnelendi\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/haberkuzey.com\\\/index.php\\\/2024\\\/07\\\/24\\\/nehir-oyunu-portekizde-sahnelendi\\\/\",\"url\":\"https:\\\/\\\/haberkuzey.com\\\/index.php\\\/2024\\\/07\\\/24\\\/nehir-oyunu-portekizde-sahnelendi\\\/\",\"name\":\"\u2018Nehir\u2019 oyunu Portekiz\u2019de sahnelendi - Haber Kuzey\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/haberkuzey.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/haberkuzey.com\\\/index.php\\\/2024\\\/07\\\/24\\\/nehir-oyunu-portekizde-sahnelendi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/haberkuzey.com\\\/index.php\\\/2024\\\/07\\\/24\\\/nehir-oyunu-portekizde-sahnelendi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/haberkuzey.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/546464.jpg\",\"datePublished\":\"2024-07-24T10:51:22+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/haberkuzey.com\\\/#\\\/schema\\\/person\\\/3372109ec735f9333f4fa47ebb9605ca\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/haberkuzey.com\\\/index.php\\\/2024\\\/07\\\/24\\\/nehir-oyunu-portekizde-sahnelendi\\\/#breadcrumb\"},\"inLanguage\":\"tr\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/haberkuzey.com\\\/index.php\\\/2024\\\/07\\\/24\\\/nehir-oyunu-portekizde-sahnelendi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"tr\",\"@id\":\"https:\\\/\\\/haberkuzey.com\\\/index.php\\\/2024\\\/07\\\/24\\\/nehir-oyunu-portekizde-sahnelendi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/haberkuzey.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/546464.jpg\",\"contentUrl\":\"https:\\\/\\\/haberkuzey.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/546464.jpg\",\"width\":1077,\"height\":519},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/haberkuzey.com\\\/index.php\\\/2024\\\/07\\\/24\\\/nehir-oyunu-portekizde-sahnelendi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Anasayfa\",\"item\":\"https:\\\/\\\/haberkuzey.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u2018Nehir\u2019 oyunu Portekiz\u2019de sahnelendi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/haberkuzey.com\\\/#website\",\"url\":\"https:\\\/\\\/haberkuzey.com\\\/\",\"name\":\"Haber Kuzey\",\"description\":\"Do\u011fru Haberin Adresi\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/haberkuzey.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"tr\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/haberkuzey.com\\\/#\\\/schema\\\/person\\\/3372109ec735f9333f4fa47ebb9605ca\",\"name\":\"haberkuzey\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"tr\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f5fc875574b1575324358c3b9e6a32b8227aa5b74f3fa22e3cadb63e26fcc39c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f5fc875574b1575324358c3b9e6a32b8227aa5b74f3fa22e3cadb63e26fcc39c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f5fc875574b1575324358c3b9e6a32b8227aa5b74f3fa22e3cadb63e26fcc39c?s=96&d=mm&r=g\",\"caption\":\"haberkuzey\"},\"sameAs\":[\"https:\\\/\\\/haberkuzey.com\"],\"url\":\"https:\\\/\\\/haberkuzey.com\\\/index.php\\\/author\\\/haberkuzey\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u2018Nehir\u2019 oyunu Portekiz\u2019de sahnelendi - Haber Kuzey","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/haberkuzey.com\/index.php\/2024\/07\/24\/nehir-oyunu-portekizde-sahnelendi\/","og_locale":"tr_TR","og_type":"article","og_title":"\u2018Nehir\u2019 oyunu Portekiz\u2019de sahnelendi - Haber Kuzey","og_description":"Girne Tiyatro Su ve Roi Tiyatrosu\u2019nun ortak projesi \u2018Nehir\u2019 oyunu, Portekiz\u2019de d\u00fczenlenen 3. MIT24 Uluslararas\u0131 Tiyatro Festivali\u2019nde sahne ald\u0131. Yap\u0131lan a\u00e7\u0131klamaya g\u00f6re, 18 Temmuz\u2019da Portekiz\u2019in merkezinde bulunan Circus Tiyatro\u2019da g\u00f6sterilen oyunu, festival organizasyon ba\u015fkan\u0131 Rui Madera, Avrasya Tiyatrolar Birli\u011fi Ba\u015fkan\u0131 Aleksandr Kiniga, Avrasya Tiyatrolar Birli\u011fi Genel Sekreteri Kubilay Erdelikara, festivale kat\u0131lan 8 \u00fclkenin t\u00fcm oyuncular\u0131 [&hellip;]","og_url":"https:\/\/haberkuzey.com\/index.php\/2024\/07\/24\/nehir-oyunu-portekizde-sahnelendi\/","og_site_name":"Haber Kuzey","article_published_time":"2024-07-24T10:51:22+00:00","og_image":[{"url":"https:\/\/brtk.net\/wp-content\/uploads\/2024\/07\/24\/546464.jpg?ver=f65757258300f06cea0870e7644ea498","type":"","width":"","height":""}],"author":"haberkuzey","twitter_card":"summary_large_image","twitter_misc":{"Yazan:":"haberkuzey","Tahmini okuma s\u00fcresi":"1 dakika"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/haberkuzey.com\/index.php\/2024\/07\/24\/nehir-oyunu-portekizde-sahnelendi\/#article","isPartOf":{"@id":"https:\/\/haberkuzey.com\/index.php\/2024\/07\/24\/nehir-oyunu-portekizde-sahnelendi\/"},"author":{"name":"haberkuzey","@id":"https:\/\/haberkuzey.com\/#\/schema\/person\/3372109ec735f9333f4fa47ebb9605ca"},"headline":"\u2018Nehir\u2019 oyunu Portekiz\u2019de sahnelendi","datePublished":"2024-07-24T10:51:22+00:00","mainEntityOfPage":{"@id":"https:\/\/haberkuzey.com\/index.php\/2024\/07\/24\/nehir-oyunu-portekizde-sahnelendi\/"},"wordCount":200,"commentCount":0,"image":{"@id":"https:\/\/haberkuzey.com\/index.php\/2024\/07\/24\/nehir-oyunu-portekizde-sahnelendi\/#primaryimage"},"thumbnailUrl":"https:\/\/haberkuzey.com\/wp-content\/uploads\/2024\/07\/546464.jpg","articleSection":["T\u00fcrkiye"],"inLanguage":"tr","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/haberkuzey.com\/index.php\/2024\/07\/24\/nehir-oyunu-portekizde-sahnelendi\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/haberkuzey.com\/index.php\/2024\/07\/24\/nehir-oyunu-portekizde-sahnelendi\/","url":"https:\/\/haberkuzey.com\/index.php\/2024\/07\/24\/nehir-oyunu-portekizde-sahnelendi\/","name":"\u2018Nehir\u2019 oyunu Portekiz\u2019de sahnelendi - Haber Kuzey","isPartOf":{"@id":"https:\/\/haberkuzey.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/haberkuzey.com\/index.php\/2024\/07\/24\/nehir-oyunu-portekizde-sahnelendi\/#primaryimage"},"image":{"@id":"https:\/\/haberkuzey.com\/index.php\/2024\/07\/24\/nehir-oyunu-portekizde-sahnelendi\/#primaryimage"},"thumbnailUrl":"https:\/\/haberkuzey.com\/wp-content\/uploads\/2024\/07\/546464.jpg","datePublished":"2024-07-24T10:51:22+00:00","author":{"@id":"https:\/\/haberkuzey.com\/#\/schema\/person\/3372109ec735f9333f4fa47ebb9605ca"},"breadcrumb":{"@id":"https:\/\/haberkuzey.com\/index.php\/2024\/07\/24\/nehir-oyunu-portekizde-sahnelendi\/#breadcrumb"},"inLanguage":"tr","potentialAction":[{"@type":"ReadAction","target":["https:\/\/haberkuzey.com\/index.php\/2024\/07\/24\/nehir-oyunu-portekizde-sahnelendi\/"]}]},{"@type":"ImageObject","inLanguage":"tr","@id":"https:\/\/haberkuzey.com\/index.php\/2024\/07\/24\/nehir-oyunu-portekizde-sahnelendi\/#primaryimage","url":"https:\/\/haberkuzey.com\/wp-content\/uploads\/2024\/07\/546464.jpg","contentUrl":"https:\/\/haberkuzey.com\/wp-content\/uploads\/2024\/07\/546464.jpg","width":1077,"height":519},{"@type":"BreadcrumbList","@id":"https:\/\/haberkuzey.com\/index.php\/2024\/07\/24\/nehir-oyunu-portekizde-sahnelendi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Anasayfa","item":"https:\/\/haberkuzey.com\/"},{"@type":"ListItem","position":2,"name":"\u2018Nehir\u2019 oyunu Portekiz\u2019de sahnelendi"}]},{"@type":"WebSite","@id":"https:\/\/haberkuzey.com\/#website","url":"https:\/\/haberkuzey.com\/","name":"Haber Kuzey","description":"Do\u011fru Haberin Adresi","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/haberkuzey.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"tr"},{"@type":"Person","@id":"https:\/\/haberkuzey.com\/#\/schema\/person\/3372109ec735f9333f4fa47ebb9605ca","name":"haberkuzey","image":{"@type":"ImageObject","inLanguage":"tr","@id":"https:\/\/secure.gravatar.com\/avatar\/f5fc875574b1575324358c3b9e6a32b8227aa5b74f3fa22e3cadb63e26fcc39c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f5fc875574b1575324358c3b9e6a32b8227aa5b74f3fa22e3cadb63e26fcc39c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f5fc875574b1575324358c3b9e6a32b8227aa5b74f3fa22e3cadb63e26fcc39c?s=96&d=mm&r=g","caption":"haberkuzey"},"sameAs":["https:\/\/haberkuzey.com"],"url":"https:\/\/haberkuzey.com\/index.php\/author\/haberkuzey\/"}]}},"_links":{"self":[{"href":"https:\/\/haberkuzey.com\/index.php\/wp-json\/wp\/v2\/posts\/6733","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/haberkuzey.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/haberkuzey.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/haberkuzey.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/haberkuzey.com\/index.php\/wp-json\/wp\/v2\/comments?post=6733"}],"version-history":[{"count":0,"href":"https:\/\/haberkuzey.com\/index.php\/wp-json\/wp\/v2\/posts\/6733\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/haberkuzey.com\/index.php\/wp-json\/wp\/v2\/media\/6734"}],"wp:attachment":[{"href":"https:\/\/haberkuzey.com\/index.php\/wp-json\/wp\/v2\/media?parent=6733"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/haberkuzey.com\/index.php\/wp-json\/wp\/v2\/categories?post=6733"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/haberkuzey.com\/index.php\/wp-json\/wp\/v2\/tags?post=6733"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}