{"id":33672,"date":"2026-01-11T06:41:36","date_gmt":"2026-01-11T04:41:36","guid":{"rendered":"https:\/\/haberkuzey.com\/index.php\/2026\/01\/11\/von-der-leyen-avrupa-suriyenin-toparlanmasi-ve-yeniden-insasi-icin-elinden-geleni-yapacak\/"},"modified":"2026-01-11T06:41:36","modified_gmt":"2026-01-11T04:41:36","slug":"von-der-leyen-avrupa-suriyenin-toparlanmasi-ve-yeniden-insasi-icin-elinden-geleni-yapacak","status":"publish","type":"post","link":"https:\/\/haberkuzey.com\/index.php\/2026\/01\/11\/von-der-leyen-avrupa-suriyenin-toparlanmasi-ve-yeniden-insasi-icin-elinden-geleni-yapacak\/","title":{"rendered":"Von der Leyen: Avrupa, Suriye&#039;nin toparlanmas\u0131 ve yeniden in\u015fas\u0131 i\u00e7in elinden geleni yapacak"},"content":{"rendered":"<p><\/p>\n<div>\n<p>&#13;<br \/>\n\tVon der Leyen ile Costa, \u015eam&#8217;da Suriye Cumhurba\u015fkan\u0131 Ahmed \u015eara ile bir araya gelmelerinin ard\u0131ndan a\u00e7\u0131klama yapt\u0131.<\/p>\n<p>&#13;<br \/>\n\tVon der Leyen, ABD merkezli X \u015firketinin sosyal medya platformundan yapt\u0131\u011f\u0131 payla\u015f\u0131mda, &#8220;On y\u0131llarca s\u00fcren korku ve sessizli\u011fin ard\u0131ndan Suriyeliler umut ve yenilenmeye do\u011fru uzun bir yolculu\u011fa ba\u015flad\u0131. Avrupa, Suriye&#8217;nin toparlanmas\u0131 ve yeniden in\u015fas\u0131 i\u00e7in elinden geleni yapacak.&#8221; ifadelerini kulland\u0131.<\/p>\n<p>&#13;<br \/>\n\tCosta da &#8220;Uzun y\u0131llar s\u00fcren sava\u015f ve ac\u0131dan sonra, (Be\u015f\u015far) Esed rejiminin d\u00fc\u015f\u00fc\u015f\u00fc nihayet Suriye halk\u0131na bir umut \u0131\u015f\u0131\u011f\u0131 oldu. AB&#8217;nin Suriye&#8217;ye olan s\u00fcrekli deste\u011fini g\u00f6stermek i\u00e7in bug\u00fcn buraday\u0131z. \u00d6n\u00fcm\u00fczde hala uzun bir yol var ama siz ilk ad\u0131mlar\u0131 \u00e7oktan att\u0131n\u0131z.&#8221; de\u011ferlendirmesinde bulundu.<\/p>\n<p>&#13;<br \/>\n\tBu temas, Aral\u0131k 2024&#8217;te Esed rejiminin devrilmesinin ard\u0131ndan AB&#8217;den Suriye&#8217;ye yap\u0131lan en \u00fcst d\u00fczeyli ziyaret oldu.<\/p>\n<p>&#13;<br \/>\n\tAB, 20 May\u0131s 2025&#8217;te Suriye&#8217;ye y\u00f6nelik yapt\u0131r\u0131mlar\u0131 kald\u0131rm\u0131\u015ft\u0131.<\/p>\n<p>&#13;<br \/>\n\tAB Komisyonunun Akdeniz&#8217;den sorumlu \u00fcyesi Dubravka Suica, Haziran 2025&#8217;te Suriye&#8217;yi ziyaret ederek, \u00fclkenin yeni y\u00f6netimiyle istikrarl\u0131 ve m\u00fcreffeh bir devlete d\u00f6n\u00fc\u015fmesine y\u00f6nelik AB&#8217;nin deste\u011fini iletmi\u015fti.<\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>&#13; Von der Leyen ile Costa, \u015eam&#8217;da Suriye Cumhurba\u015fkan\u0131 Ahmed \u015eara ile bir araya gelmelerinin ard\u0131ndan a\u00e7\u0131klama yapt\u0131. &#13; Von der Leyen, ABD merkezli X \u015firketinin sosyal medya platformundan yapt\u0131\u011f\u0131 payla\u015f\u0131mda, &#8220;On y\u0131llarca s\u00fcren korku ve sessizli\u011fin ard\u0131ndan Suriyeliler umut ve yenilenmeye do\u011fru uzun bir yolculu\u011fa ba\u015flad\u0131. Avrupa, Suriye&#8217;nin toparlanmas\u0131 ve yeniden in\u015fas\u0131 i\u00e7in elinden [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2381,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"footnotes":""},"categories":[2],"tags":[],"class_list":["post-33672","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dunya"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Von der Leyen: Avrupa, Suriye&#039;nin toparlanmas\u0131 ve yeniden in\u015fas\u0131 i\u00e7in elinden geleni yapacak - Haber Kuzey<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/haberkuzey.com\/index.php\/2026\/01\/11\/von-der-leyen-avrupa-suriyenin-toparlanmasi-ve-yeniden-insasi-icin-elinden-geleni-yapacak\/\" \/>\n<meta property=\"og:locale\" content=\"tr_TR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Von der Leyen: Avrupa, Suriye&#039;nin toparlanmas\u0131 ve yeniden in\u015fas\u0131 i\u00e7in elinden geleni yapacak - Haber Kuzey\" \/>\n<meta property=\"og:description\" content=\"&#013; Von der Leyen ile Costa, \u015eam&#8217;da Suriye Cumhurba\u015fkan\u0131 Ahmed \u015eara ile bir araya gelmelerinin ard\u0131ndan a\u00e7\u0131klama yapt\u0131. &#013; Von der Leyen, ABD merkezli X \u015firketinin sosyal medya platformundan yapt\u0131\u011f\u0131 payla\u015f\u0131mda, &#8220;On y\u0131llarca s\u00fcren korku ve sessizli\u011fin ard\u0131ndan Suriyeliler umut ve yenilenmeye do\u011fru uzun bir yolculu\u011fa ba\u015flad\u0131. Avrupa, Suriye&#8217;nin toparlanmas\u0131 ve yeniden in\u015fas\u0131 i\u00e7in elinden [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/haberkuzey.com\/index.php\/2026\/01\/11\/von-der-leyen-avrupa-suriyenin-toparlanmasi-ve-yeniden-insasi-icin-elinden-geleni-yapacak\/\" \/>\n<meta property=\"og:site_name\" content=\"Haber Kuzey\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-11T04:41:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/trthaberstatic.cdn.wp.trt.com.tr\/resimler\/1662000\/ursula-von-der-leyen-aa-1663244.jpg\" \/>\n<meta name=\"author\" content=\"haberkuzey\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Yazan:\" \/>\n\t<meta name=\"twitter:data1\" content=\"haberkuzey\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tahmini okuma s\u00fcresi\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 dakika\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/haberkuzey.com\\\/index.php\\\/2026\\\/01\\\/11\\\/von-der-leyen-avrupa-suriyenin-toparlanmasi-ve-yeniden-insasi-icin-elinden-geleni-yapacak\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/haberkuzey.com\\\/index.php\\\/2026\\\/01\\\/11\\\/von-der-leyen-avrupa-suriyenin-toparlanmasi-ve-yeniden-insasi-icin-elinden-geleni-yapacak\\\/\"},\"author\":{\"name\":\"haberkuzey\",\"@id\":\"https:\\\/\\\/haberkuzey.com\\\/#\\\/schema\\\/person\\\/3372109ec735f9333f4fa47ebb9605ca\"},\"headline\":\"Von der Leyen: Avrupa, Suriye&#039;nin toparlanmas\u0131 ve yeniden in\u015fas\u0131 i\u00e7in elinden geleni yapacak\",\"datePublished\":\"2026-01-11T04:41:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/haberkuzey.com\\\/index.php\\\/2026\\\/01\\\/11\\\/von-der-leyen-avrupa-suriyenin-toparlanmasi-ve-yeniden-insasi-icin-elinden-geleni-yapacak\\\/\"},\"wordCount\":220,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/haberkuzey.com\\\/index.php\\\/2026\\\/01\\\/11\\\/von-der-leyen-avrupa-suriyenin-toparlanmasi-ve-yeniden-insasi-icin-elinden-geleni-yapacak\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/haberkuzey.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/ursula-von-der-leyen-aa-1663244.jpg\",\"articleSection\":[\"D\u00fcnya\"],\"inLanguage\":\"tr\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/haberkuzey.com\\\/index.php\\\/2026\\\/01\\\/11\\\/von-der-leyen-avrupa-suriyenin-toparlanmasi-ve-yeniden-insasi-icin-elinden-geleni-yapacak\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/haberkuzey.com\\\/index.php\\\/2026\\\/01\\\/11\\\/von-der-leyen-avrupa-suriyenin-toparlanmasi-ve-yeniden-insasi-icin-elinden-geleni-yapacak\\\/\",\"url\":\"https:\\\/\\\/haberkuzey.com\\\/index.php\\\/2026\\\/01\\\/11\\\/von-der-leyen-avrupa-suriyenin-toparlanmasi-ve-yeniden-insasi-icin-elinden-geleni-yapacak\\\/\",\"name\":\"Von der Leyen: Avrupa, Suriye&#039;nin toparlanmas\u0131 ve yeniden in\u015fas\u0131 i\u00e7in elinden geleni yapacak - Haber Kuzey\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/haberkuzey.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/haberkuzey.com\\\/index.php\\\/2026\\\/01\\\/11\\\/von-der-leyen-avrupa-suriyenin-toparlanmasi-ve-yeniden-insasi-icin-elinden-geleni-yapacak\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/haberkuzey.com\\\/index.php\\\/2026\\\/01\\\/11\\\/von-der-leyen-avrupa-suriyenin-toparlanmasi-ve-yeniden-insasi-icin-elinden-geleni-yapacak\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/haberkuzey.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/ursula-von-der-leyen-aa-1663244.jpg\",\"datePublished\":\"2026-01-11T04:41:36+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/haberkuzey.com\\\/#\\\/schema\\\/person\\\/3372109ec735f9333f4fa47ebb9605ca\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/haberkuzey.com\\\/index.php\\\/2026\\\/01\\\/11\\\/von-der-leyen-avrupa-suriyenin-toparlanmasi-ve-yeniden-insasi-icin-elinden-geleni-yapacak\\\/#breadcrumb\"},\"inLanguage\":\"tr\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/haberkuzey.com\\\/index.php\\\/2026\\\/01\\\/11\\\/von-der-leyen-avrupa-suriyenin-toparlanmasi-ve-yeniden-insasi-icin-elinden-geleni-yapacak\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"tr\",\"@id\":\"https:\\\/\\\/haberkuzey.com\\\/index.php\\\/2026\\\/01\\\/11\\\/von-der-leyen-avrupa-suriyenin-toparlanmasi-ve-yeniden-insasi-icin-elinden-geleni-yapacak\\\/#primaryimage\",\"url\":\"https:\\\/\\\/haberkuzey.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/ursula-von-der-leyen-aa-1663244.jpg\",\"contentUrl\":\"https:\\\/\\\/haberkuzey.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/ursula-von-der-leyen-aa-1663244.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/haberkuzey.com\\\/index.php\\\/2026\\\/01\\\/11\\\/von-der-leyen-avrupa-suriyenin-toparlanmasi-ve-yeniden-insasi-icin-elinden-geleni-yapacak\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Anasayfa\",\"item\":\"https:\\\/\\\/haberkuzey.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Von der Leyen: Avrupa, Suriye&#039;nin toparlanmas\u0131 ve yeniden in\u015fas\u0131 i\u00e7in elinden geleni yapacak\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/haberkuzey.com\\\/#website\",\"url\":\"https:\\\/\\\/haberkuzey.com\\\/\",\"name\":\"Haber Kuzey\",\"description\":\"Do\u011fru Haberin Adresi\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/haberkuzey.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"tr\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/haberkuzey.com\\\/#\\\/schema\\\/person\\\/3372109ec735f9333f4fa47ebb9605ca\",\"name\":\"haberkuzey\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"tr\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f5fc875574b1575324358c3b9e6a32b8227aa5b74f3fa22e3cadb63e26fcc39c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f5fc875574b1575324358c3b9e6a32b8227aa5b74f3fa22e3cadb63e26fcc39c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f5fc875574b1575324358c3b9e6a32b8227aa5b74f3fa22e3cadb63e26fcc39c?s=96&d=mm&r=g\",\"caption\":\"haberkuzey\"},\"sameAs\":[\"https:\\\/\\\/haberkuzey.com\"],\"url\":\"https:\\\/\\\/haberkuzey.com\\\/index.php\\\/author\\\/haberkuzey\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Von der Leyen: Avrupa, Suriye&#039;nin toparlanmas\u0131 ve yeniden in\u015fas\u0131 i\u00e7in elinden geleni yapacak - Haber Kuzey","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/haberkuzey.com\/index.php\/2026\/01\/11\/von-der-leyen-avrupa-suriyenin-toparlanmasi-ve-yeniden-insasi-icin-elinden-geleni-yapacak\/","og_locale":"tr_TR","og_type":"article","og_title":"Von der Leyen: Avrupa, Suriye&#039;nin toparlanmas\u0131 ve yeniden in\u015fas\u0131 i\u00e7in elinden geleni yapacak - Haber Kuzey","og_description":"&#13; Von der Leyen ile Costa, \u015eam&#8217;da Suriye Cumhurba\u015fkan\u0131 Ahmed \u015eara ile bir araya gelmelerinin ard\u0131ndan a\u00e7\u0131klama yapt\u0131. &#13; Von der Leyen, ABD merkezli X \u015firketinin sosyal medya platformundan yapt\u0131\u011f\u0131 payla\u015f\u0131mda, &#8220;On y\u0131llarca s\u00fcren korku ve sessizli\u011fin ard\u0131ndan Suriyeliler umut ve yenilenmeye do\u011fru uzun bir yolculu\u011fa ba\u015flad\u0131. Avrupa, Suriye&#8217;nin toparlanmas\u0131 ve yeniden in\u015fas\u0131 i\u00e7in elinden [&hellip;]","og_url":"https:\/\/haberkuzey.com\/index.php\/2026\/01\/11\/von-der-leyen-avrupa-suriyenin-toparlanmasi-ve-yeniden-insasi-icin-elinden-geleni-yapacak\/","og_site_name":"Haber Kuzey","article_published_time":"2026-01-11T04:41:36+00:00","og_image":[{"url":"https:\/\/trthaberstatic.cdn.wp.trt.com.tr\/resimler\/1662000\/ursula-von-der-leyen-aa-1663244.jpg","type":"","width":"","height":""}],"author":"haberkuzey","twitter_card":"summary_large_image","twitter_misc":{"Yazan:":"haberkuzey","Tahmini okuma s\u00fcresi":"1 dakika"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/haberkuzey.com\/index.php\/2026\/01\/11\/von-der-leyen-avrupa-suriyenin-toparlanmasi-ve-yeniden-insasi-icin-elinden-geleni-yapacak\/#article","isPartOf":{"@id":"https:\/\/haberkuzey.com\/index.php\/2026\/01\/11\/von-der-leyen-avrupa-suriyenin-toparlanmasi-ve-yeniden-insasi-icin-elinden-geleni-yapacak\/"},"author":{"name":"haberkuzey","@id":"https:\/\/haberkuzey.com\/#\/schema\/person\/3372109ec735f9333f4fa47ebb9605ca"},"headline":"Von der Leyen: Avrupa, Suriye&#039;nin toparlanmas\u0131 ve yeniden in\u015fas\u0131 i\u00e7in elinden geleni yapacak","datePublished":"2026-01-11T04:41:36+00:00","mainEntityOfPage":{"@id":"https:\/\/haberkuzey.com\/index.php\/2026\/01\/11\/von-der-leyen-avrupa-suriyenin-toparlanmasi-ve-yeniden-insasi-icin-elinden-geleni-yapacak\/"},"wordCount":220,"commentCount":0,"image":{"@id":"https:\/\/haberkuzey.com\/index.php\/2026\/01\/11\/von-der-leyen-avrupa-suriyenin-toparlanmasi-ve-yeniden-insasi-icin-elinden-geleni-yapacak\/#primaryimage"},"thumbnailUrl":"https:\/\/haberkuzey.com\/wp-content\/uploads\/2024\/05\/ursula-von-der-leyen-aa-1663244.jpg","articleSection":["D\u00fcnya"],"inLanguage":"tr","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/haberkuzey.com\/index.php\/2026\/01\/11\/von-der-leyen-avrupa-suriyenin-toparlanmasi-ve-yeniden-insasi-icin-elinden-geleni-yapacak\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/haberkuzey.com\/index.php\/2026\/01\/11\/von-der-leyen-avrupa-suriyenin-toparlanmasi-ve-yeniden-insasi-icin-elinden-geleni-yapacak\/","url":"https:\/\/haberkuzey.com\/index.php\/2026\/01\/11\/von-der-leyen-avrupa-suriyenin-toparlanmasi-ve-yeniden-insasi-icin-elinden-geleni-yapacak\/","name":"Von der Leyen: Avrupa, Suriye&#039;nin toparlanmas\u0131 ve yeniden in\u015fas\u0131 i\u00e7in elinden geleni yapacak - Haber Kuzey","isPartOf":{"@id":"https:\/\/haberkuzey.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/haberkuzey.com\/index.php\/2026\/01\/11\/von-der-leyen-avrupa-suriyenin-toparlanmasi-ve-yeniden-insasi-icin-elinden-geleni-yapacak\/#primaryimage"},"image":{"@id":"https:\/\/haberkuzey.com\/index.php\/2026\/01\/11\/von-der-leyen-avrupa-suriyenin-toparlanmasi-ve-yeniden-insasi-icin-elinden-geleni-yapacak\/#primaryimage"},"thumbnailUrl":"https:\/\/haberkuzey.com\/wp-content\/uploads\/2024\/05\/ursula-von-der-leyen-aa-1663244.jpg","datePublished":"2026-01-11T04:41:36+00:00","author":{"@id":"https:\/\/haberkuzey.com\/#\/schema\/person\/3372109ec735f9333f4fa47ebb9605ca"},"breadcrumb":{"@id":"https:\/\/haberkuzey.com\/index.php\/2026\/01\/11\/von-der-leyen-avrupa-suriyenin-toparlanmasi-ve-yeniden-insasi-icin-elinden-geleni-yapacak\/#breadcrumb"},"inLanguage":"tr","potentialAction":[{"@type":"ReadAction","target":["https:\/\/haberkuzey.com\/index.php\/2026\/01\/11\/von-der-leyen-avrupa-suriyenin-toparlanmasi-ve-yeniden-insasi-icin-elinden-geleni-yapacak\/"]}]},{"@type":"ImageObject","inLanguage":"tr","@id":"https:\/\/haberkuzey.com\/index.php\/2026\/01\/11\/von-der-leyen-avrupa-suriyenin-toparlanmasi-ve-yeniden-insasi-icin-elinden-geleni-yapacak\/#primaryimage","url":"https:\/\/haberkuzey.com\/wp-content\/uploads\/2024\/05\/ursula-von-der-leyen-aa-1663244.jpg","contentUrl":"https:\/\/haberkuzey.com\/wp-content\/uploads\/2024\/05\/ursula-von-der-leyen-aa-1663244.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/haberkuzey.com\/index.php\/2026\/01\/11\/von-der-leyen-avrupa-suriyenin-toparlanmasi-ve-yeniden-insasi-icin-elinden-geleni-yapacak\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Anasayfa","item":"https:\/\/haberkuzey.com\/"},{"@type":"ListItem","position":2,"name":"Von der Leyen: Avrupa, Suriye&#039;nin toparlanmas\u0131 ve yeniden in\u015fas\u0131 i\u00e7in elinden geleni yapacak"}]},{"@type":"WebSite","@id":"https:\/\/haberkuzey.com\/#website","url":"https:\/\/haberkuzey.com\/","name":"Haber Kuzey","description":"Do\u011fru Haberin Adresi","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/haberkuzey.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"tr"},{"@type":"Person","@id":"https:\/\/haberkuzey.com\/#\/schema\/person\/3372109ec735f9333f4fa47ebb9605ca","name":"haberkuzey","image":{"@type":"ImageObject","inLanguage":"tr","@id":"https:\/\/secure.gravatar.com\/avatar\/f5fc875574b1575324358c3b9e6a32b8227aa5b74f3fa22e3cadb63e26fcc39c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f5fc875574b1575324358c3b9e6a32b8227aa5b74f3fa22e3cadb63e26fcc39c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f5fc875574b1575324358c3b9e6a32b8227aa5b74f3fa22e3cadb63e26fcc39c?s=96&d=mm&r=g","caption":"haberkuzey"},"sameAs":["https:\/\/haberkuzey.com"],"url":"https:\/\/haberkuzey.com\/index.php\/author\/haberkuzey\/"}]}},"_links":{"self":[{"href":"https:\/\/haberkuzey.com\/index.php\/wp-json\/wp\/v2\/posts\/33672","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/haberkuzey.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/haberkuzey.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/haberkuzey.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/haberkuzey.com\/index.php\/wp-json\/wp\/v2\/comments?post=33672"}],"version-history":[{"count":0,"href":"https:\/\/haberkuzey.com\/index.php\/wp-json\/wp\/v2\/posts\/33672\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/haberkuzey.com\/index.php\/wp-json\/wp\/v2\/media\/2381"}],"wp:attachment":[{"href":"https:\/\/haberkuzey.com\/index.php\/wp-json\/wp\/v2\/media?parent=33672"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/haberkuzey.com\/index.php\/wp-json\/wp\/v2\/categories?post=33672"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/haberkuzey.com\/index.php\/wp-json\/wp\/v2\/tags?post=33672"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}