{"id":29320,"date":"2025-08-29T13:07:35","date_gmt":"2025-08-29T10:07:35","guid":{"rendered":"https:\/\/haberkuzey.com\/index.php\/2025\/08\/29\/12-dev-adam-bugun-parkeye-cikiyor\/"},"modified":"2025-08-29T13:07:35","modified_gmt":"2025-08-29T10:07:35","slug":"12-dev-adam-bugun-parkeye-cikiyor","status":"publish","type":"post","link":"https:\/\/haberkuzey.com\/index.php\/2025\/08\/29\/12-dev-adam-bugun-parkeye-cikiyor\/","title":{"rendered":"12 Dev Adam bug\u00fcn parkeye \u00e7\u0131k\u0131yor"},"content":{"rendered":"<p><\/p>\n<article>\n<header><\/p>\n<h2>A Milli Erkek Basketbol Tak\u0131m\u0131, 2025 Avrupa \u015eampiyonas\u0131 A Grubu&#8217;ndaki ikinci ma\u00e7\u0131nda bug\u00fcn \u00c7ekya ile kar\u015f\u0131 kar\u015f\u0131ya gelecek.<\/h2>\n<p>29\/08\/2025 12:25<\/header>\n<footer><small>\u00a9 TRT HABER<\/small><\/footer>\n<\/article>\n","protected":false},"excerpt":{"rendered":"<p>A Milli Erkek Basketbol Tak\u0131m\u0131, 2025 Avrupa \u015eampiyonas\u0131 A Grubu&#8217;ndaki ikinci ma\u00e7\u0131nda bug\u00fcn \u00c7ekya ile kar\u015f\u0131 kar\u015f\u0131ya gelecek. 29\/08\/2025 12:25 \u00a9 TRT HABER<\/p>\n","protected":false},"author":1,"featured_media":29321,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"footnotes":""},"categories":[4],"tags":[],"class_list":["post-29320","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-spor"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>12 Dev Adam bug\u00fcn parkeye \u00e7\u0131k\u0131yor - Haber Kuzey<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/haberkuzey.com\/index.php\/2025\/08\/29\/12-dev-adam-bugun-parkeye-cikiyor\/\" \/>\n<meta property=\"og:locale\" content=\"tr_TR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"12 Dev Adam bug\u00fcn parkeye \u00e7\u0131k\u0131yor - Haber Kuzey\" \/>\n<meta property=\"og:description\" content=\"A Milli Erkek Basketbol Tak\u0131m\u0131, 2025 Avrupa \u015eampiyonas\u0131 A Grubu&#8217;ndaki ikinci ma\u00e7\u0131nda bug\u00fcn \u00c7ekya ile kar\u015f\u0131 kar\u015f\u0131ya gelecek. 29\/08\/2025 12:25 \u00a9 TRT HABER\" \/>\n<meta property=\"og:url\" content=\"https:\/\/haberkuzey.com\/index.php\/2025\/08\/29\/12-dev-adam-bugun-parkeye-cikiyor\/\" \/>\n<meta property=\"og:site_name\" content=\"Haber Kuzey\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-29T10:07:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/trthaberstatic.cdn.wp.trt.com.tr\/resimler\/2392000\/12-dev-adamaa-2393084.jpg\" \/>\n<meta name=\"author\" content=\"haberkuzey\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Yazan:\" \/>\n\t<meta name=\"twitter:data1\" content=\"haberkuzey\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/haberkuzey.com\\\/index.php\\\/2025\\\/08\\\/29\\\/12-dev-adam-bugun-parkeye-cikiyor\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/haberkuzey.com\\\/index.php\\\/2025\\\/08\\\/29\\\/12-dev-adam-bugun-parkeye-cikiyor\\\/\"},\"author\":{\"name\":\"haberkuzey\",\"@id\":\"https:\\\/\\\/haberkuzey.com\\\/#\\\/schema\\\/person\\\/3372109ec735f9333f4fa47ebb9605ca\"},\"headline\":\"12 Dev Adam bug\u00fcn parkeye \u00e7\u0131k\u0131yor\",\"datePublished\":\"2025-08-29T10:07:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/haberkuzey.com\\\/index.php\\\/2025\\\/08\\\/29\\\/12-dev-adam-bugun-parkeye-cikiyor\\\/\"},\"wordCount\":31,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/haberkuzey.com\\\/index.php\\\/2025\\\/08\\\/29\\\/12-dev-adam-bugun-parkeye-cikiyor\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/haberkuzey.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/12-dev-adamaa-2393084.jpg\",\"articleSection\":[\"Spor\"],\"inLanguage\":\"tr\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/haberkuzey.com\\\/index.php\\\/2025\\\/08\\\/29\\\/12-dev-adam-bugun-parkeye-cikiyor\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/haberkuzey.com\\\/index.php\\\/2025\\\/08\\\/29\\\/12-dev-adam-bugun-parkeye-cikiyor\\\/\",\"url\":\"https:\\\/\\\/haberkuzey.com\\\/index.php\\\/2025\\\/08\\\/29\\\/12-dev-adam-bugun-parkeye-cikiyor\\\/\",\"name\":\"12 Dev Adam bug\u00fcn parkeye \u00e7\u0131k\u0131yor - Haber Kuzey\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/haberkuzey.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/haberkuzey.com\\\/index.php\\\/2025\\\/08\\\/29\\\/12-dev-adam-bugun-parkeye-cikiyor\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/haberkuzey.com\\\/index.php\\\/2025\\\/08\\\/29\\\/12-dev-adam-bugun-parkeye-cikiyor\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/haberkuzey.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/12-dev-adamaa-2393084.jpg\",\"datePublished\":\"2025-08-29T10:07:35+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/haberkuzey.com\\\/#\\\/schema\\\/person\\\/3372109ec735f9333f4fa47ebb9605ca\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/haberkuzey.com\\\/index.php\\\/2025\\\/08\\\/29\\\/12-dev-adam-bugun-parkeye-cikiyor\\\/#breadcrumb\"},\"inLanguage\":\"tr\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/haberkuzey.com\\\/index.php\\\/2025\\\/08\\\/29\\\/12-dev-adam-bugun-parkeye-cikiyor\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"tr\",\"@id\":\"https:\\\/\\\/haberkuzey.com\\\/index.php\\\/2025\\\/08\\\/29\\\/12-dev-adam-bugun-parkeye-cikiyor\\\/#primaryimage\",\"url\":\"https:\\\/\\\/haberkuzey.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/12-dev-adamaa-2393084.jpg\",\"contentUrl\":\"https:\\\/\\\/haberkuzey.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/12-dev-adamaa-2393084.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/haberkuzey.com\\\/index.php\\\/2025\\\/08\\\/29\\\/12-dev-adam-bugun-parkeye-cikiyor\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Anasayfa\",\"item\":\"https:\\\/\\\/haberkuzey.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"12 Dev Adam bug\u00fcn parkeye \u00e7\u0131k\u0131yor\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/haberkuzey.com\\\/#website\",\"url\":\"https:\\\/\\\/haberkuzey.com\\\/\",\"name\":\"Haber Kuzey\",\"description\":\"Do\u011fru Haberin Adresi\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/haberkuzey.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"tr\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/haberkuzey.com\\\/#\\\/schema\\\/person\\\/3372109ec735f9333f4fa47ebb9605ca\",\"name\":\"haberkuzey\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"tr\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f5fc875574b1575324358c3b9e6a32b8227aa5b74f3fa22e3cadb63e26fcc39c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f5fc875574b1575324358c3b9e6a32b8227aa5b74f3fa22e3cadb63e26fcc39c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f5fc875574b1575324358c3b9e6a32b8227aa5b74f3fa22e3cadb63e26fcc39c?s=96&d=mm&r=g\",\"caption\":\"haberkuzey\"},\"sameAs\":[\"https:\\\/\\\/haberkuzey.com\"],\"url\":\"https:\\\/\\\/haberkuzey.com\\\/index.php\\\/author\\\/haberkuzey\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"12 Dev Adam bug\u00fcn parkeye \u00e7\u0131k\u0131yor - Haber Kuzey","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/haberkuzey.com\/index.php\/2025\/08\/29\/12-dev-adam-bugun-parkeye-cikiyor\/","og_locale":"tr_TR","og_type":"article","og_title":"12 Dev Adam bug\u00fcn parkeye \u00e7\u0131k\u0131yor - Haber Kuzey","og_description":"A Milli Erkek Basketbol Tak\u0131m\u0131, 2025 Avrupa \u015eampiyonas\u0131 A Grubu&#8217;ndaki ikinci ma\u00e7\u0131nda bug\u00fcn \u00c7ekya ile kar\u015f\u0131 kar\u015f\u0131ya gelecek. 29\/08\/2025 12:25 \u00a9 TRT HABER","og_url":"https:\/\/haberkuzey.com\/index.php\/2025\/08\/29\/12-dev-adam-bugun-parkeye-cikiyor\/","og_site_name":"Haber Kuzey","article_published_time":"2025-08-29T10:07:35+00:00","og_image":[{"url":"https:\/\/trthaberstatic.cdn.wp.trt.com.tr\/resimler\/2392000\/12-dev-adamaa-2393084.jpg","type":"","width":"","height":""}],"author":"haberkuzey","twitter_card":"summary_large_image","twitter_misc":{"Yazan:":"haberkuzey"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/haberkuzey.com\/index.php\/2025\/08\/29\/12-dev-adam-bugun-parkeye-cikiyor\/#article","isPartOf":{"@id":"https:\/\/haberkuzey.com\/index.php\/2025\/08\/29\/12-dev-adam-bugun-parkeye-cikiyor\/"},"author":{"name":"haberkuzey","@id":"https:\/\/haberkuzey.com\/#\/schema\/person\/3372109ec735f9333f4fa47ebb9605ca"},"headline":"12 Dev Adam bug\u00fcn parkeye \u00e7\u0131k\u0131yor","datePublished":"2025-08-29T10:07:35+00:00","mainEntityOfPage":{"@id":"https:\/\/haberkuzey.com\/index.php\/2025\/08\/29\/12-dev-adam-bugun-parkeye-cikiyor\/"},"wordCount":31,"commentCount":0,"image":{"@id":"https:\/\/haberkuzey.com\/index.php\/2025\/08\/29\/12-dev-adam-bugun-parkeye-cikiyor\/#primaryimage"},"thumbnailUrl":"https:\/\/haberkuzey.com\/wp-content\/uploads\/2025\/08\/12-dev-adamaa-2393084.jpg","articleSection":["Spor"],"inLanguage":"tr","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/haberkuzey.com\/index.php\/2025\/08\/29\/12-dev-adam-bugun-parkeye-cikiyor\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/haberkuzey.com\/index.php\/2025\/08\/29\/12-dev-adam-bugun-parkeye-cikiyor\/","url":"https:\/\/haberkuzey.com\/index.php\/2025\/08\/29\/12-dev-adam-bugun-parkeye-cikiyor\/","name":"12 Dev Adam bug\u00fcn parkeye \u00e7\u0131k\u0131yor - Haber Kuzey","isPartOf":{"@id":"https:\/\/haberkuzey.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/haberkuzey.com\/index.php\/2025\/08\/29\/12-dev-adam-bugun-parkeye-cikiyor\/#primaryimage"},"image":{"@id":"https:\/\/haberkuzey.com\/index.php\/2025\/08\/29\/12-dev-adam-bugun-parkeye-cikiyor\/#primaryimage"},"thumbnailUrl":"https:\/\/haberkuzey.com\/wp-content\/uploads\/2025\/08\/12-dev-adamaa-2393084.jpg","datePublished":"2025-08-29T10:07:35+00:00","author":{"@id":"https:\/\/haberkuzey.com\/#\/schema\/person\/3372109ec735f9333f4fa47ebb9605ca"},"breadcrumb":{"@id":"https:\/\/haberkuzey.com\/index.php\/2025\/08\/29\/12-dev-adam-bugun-parkeye-cikiyor\/#breadcrumb"},"inLanguage":"tr","potentialAction":[{"@type":"ReadAction","target":["https:\/\/haberkuzey.com\/index.php\/2025\/08\/29\/12-dev-adam-bugun-parkeye-cikiyor\/"]}]},{"@type":"ImageObject","inLanguage":"tr","@id":"https:\/\/haberkuzey.com\/index.php\/2025\/08\/29\/12-dev-adam-bugun-parkeye-cikiyor\/#primaryimage","url":"https:\/\/haberkuzey.com\/wp-content\/uploads\/2025\/08\/12-dev-adamaa-2393084.jpg","contentUrl":"https:\/\/haberkuzey.com\/wp-content\/uploads\/2025\/08\/12-dev-adamaa-2393084.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/haberkuzey.com\/index.php\/2025\/08\/29\/12-dev-adam-bugun-parkeye-cikiyor\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Anasayfa","item":"https:\/\/haberkuzey.com\/"},{"@type":"ListItem","position":2,"name":"12 Dev Adam bug\u00fcn parkeye \u00e7\u0131k\u0131yor"}]},{"@type":"WebSite","@id":"https:\/\/haberkuzey.com\/#website","url":"https:\/\/haberkuzey.com\/","name":"Haber Kuzey","description":"Do\u011fru Haberin Adresi","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/haberkuzey.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"tr"},{"@type":"Person","@id":"https:\/\/haberkuzey.com\/#\/schema\/person\/3372109ec735f9333f4fa47ebb9605ca","name":"haberkuzey","image":{"@type":"ImageObject","inLanguage":"tr","@id":"https:\/\/secure.gravatar.com\/avatar\/f5fc875574b1575324358c3b9e6a32b8227aa5b74f3fa22e3cadb63e26fcc39c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f5fc875574b1575324358c3b9e6a32b8227aa5b74f3fa22e3cadb63e26fcc39c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f5fc875574b1575324358c3b9e6a32b8227aa5b74f3fa22e3cadb63e26fcc39c?s=96&d=mm&r=g","caption":"haberkuzey"},"sameAs":["https:\/\/haberkuzey.com"],"url":"https:\/\/haberkuzey.com\/index.php\/author\/haberkuzey\/"}]}},"_links":{"self":[{"href":"https:\/\/haberkuzey.com\/index.php\/wp-json\/wp\/v2\/posts\/29320","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/haberkuzey.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/haberkuzey.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/haberkuzey.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/haberkuzey.com\/index.php\/wp-json\/wp\/v2\/comments?post=29320"}],"version-history":[{"count":0,"href":"https:\/\/haberkuzey.com\/index.php\/wp-json\/wp\/v2\/posts\/29320\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/haberkuzey.com\/index.php\/wp-json\/wp\/v2\/media\/29321"}],"wp:attachment":[{"href":"https:\/\/haberkuzey.com\/index.php\/wp-json\/wp\/v2\/media?parent=29320"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/haberkuzey.com\/index.php\/wp-json\/wp\/v2\/categories?post=29320"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/haberkuzey.com\/index.php\/wp-json\/wp\/v2\/tags?post=29320"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}