{"id":26470,"date":"2025-06-24T10:34:39","date_gmt":"2025-06-24T07:34:39","guid":{"rendered":"https:\/\/haberkuzey.com\/index.php\/2025\/06\/24\/engelsiz-sinema-salonu-ve-aktivite-merkezinde-animasyon-film-gosterimi-yapildi\/"},"modified":"2025-06-24T10:34:39","modified_gmt":"2025-06-24T07:34:39","slug":"engelsiz-sinema-salonu-ve-aktivite-merkezinde-animasyon-film-gosterimi-yapildi","status":"publish","type":"post","link":"https:\/\/haberkuzey.com\/index.php\/2025\/06\/24\/engelsiz-sinema-salonu-ve-aktivite-merkezinde-animasyon-film-gosterimi-yapildi\/","title":{"rendered":"Engelsiz Sinema Salonu ve Aktivite Merkezi\u2019nde animasyon film g\u00f6sterimi yap\u0131ld\u0131"},"content":{"rendered":"<div>\n<div class=\"mariselle-image-container none\">\n                                            <\/div>\n<p>Yak\u0131n Do\u011fu \u00dcniversitesi (YD\u00dc) ve Telsim i\u015f birli\u011finde yenilenerek kapasitesi art\u0131r\u0131lan Engelsiz Sinema Salonu ve Aktivite Merkezi\u2019nde \u00e7ocuklara y\u00f6nelik animasyon film g\u00f6sterimi yap\u0131ld\u0131.\u00a0<\/p>\n<p>Telsim\u2019den yap\u0131lan a\u00e7\u0131klamaya g\u00f6re, YD\u00dc \u0130leti\u015fim Fak\u00fcltesi\u2019nde bulunan merkezdeki etkinli\u011fe Ne\u015fe Yuvam Kre\u015f ve Et\u00fct Merkezi ile Bright Moonlight Preschool\u2019un \u00f6\u011frencileri ve sorumlu \u00f6\u011fretmenleri kat\u0131ld\u0131.<\/p>\n<p>YD\u00dc \u0130leti\u015fim Fak\u00fcltesi Dekan\u0131 Prof. Dr. Fevzi Kasap, Telsim Genel M\u00fcd\u00fcr\u00fc Sefer T\u00fcz, etkinli\u011fin koordinat\u00f6rl\u00fc\u011f\u00fcn\u00fc yapan YD\u00dc Halkla \u0130li\u015fkiler ve Tan\u0131t\u0131m B\u00f6l\u00fcm\u00fc \u00d6\u011fretim G\u00f6revlisi Ufuk Altun\u00e7 ve Telsim Kurumsal \u0130leti\u015fim M\u00fcd\u00fcr\u00fc Nil Zorlu Atai\u2019nin de yer ald\u0131\u011f\u0131 etkinlikte, \u00e7ocuklar animasyon filmi izledi.<\/p>\n<\/p><\/div>\n<p><script async\n                    defer\n                    crossorigin=\"anonymous\"\n                    src=\"https:\/\/connect.facebook.net\/tr_TR\/sdk.js#xfbml=1&#038;version=v3.3\"\n            ><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Yak\u0131n Do\u011fu \u00dcniversitesi (YD\u00dc) ve Telsim i\u015f birli\u011finde yenilenerek kapasitesi art\u0131r\u0131lan Engelsiz Sinema Salonu ve Aktivite Merkezi\u2019nde \u00e7ocuklara y\u00f6nelik animasyon film g\u00f6sterimi yap\u0131ld\u0131.\u00a0 Telsim\u2019den yap\u0131lan a\u00e7\u0131klamaya g\u00f6re, YD\u00dc \u0130leti\u015fim Fak\u00fcltesi\u2019nde bulunan merkezdeki etkinli\u011fe Ne\u015fe Yuvam Kre\u015f ve Et\u00fct Merkezi ile Bright Moonlight Preschool\u2019un \u00f6\u011frencileri ve sorumlu \u00f6\u011fretmenleri kat\u0131ld\u0131. YD\u00dc \u0130leti\u015fim Fak\u00fcltesi Dekan\u0131 Prof. Dr. Fevzi [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":26471,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-26470","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-kibris"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Engelsiz Sinema Salonu ve Aktivite Merkezi\u2019nde animasyon film g\u00f6sterimi yap\u0131ld\u0131 - Haber Kuzey<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/haberkuzey.com\/index.php\/2025\/06\/24\/engelsiz-sinema-salonu-ve-aktivite-merkezinde-animasyon-film-gosterimi-yapildi\/\" \/>\n<meta property=\"og:locale\" content=\"tr_TR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Engelsiz Sinema Salonu ve Aktivite Merkezi\u2019nde animasyon film g\u00f6sterimi yap\u0131ld\u0131 - Haber Kuzey\" \/>\n<meta property=\"og:description\" content=\"Yak\u0131n Do\u011fu \u00dcniversitesi (YD\u00dc) ve Telsim i\u015f birli\u011finde yenilenerek kapasitesi art\u0131r\u0131lan Engelsiz Sinema Salonu ve Aktivite Merkezi\u2019nde \u00e7ocuklara y\u00f6nelik animasyon film g\u00f6sterimi yap\u0131ld\u0131.\u00a0 Telsim\u2019den yap\u0131lan a\u00e7\u0131klamaya g\u00f6re, YD\u00dc \u0130leti\u015fim Fak\u00fcltesi\u2019nde bulunan merkezdeki etkinli\u011fe Ne\u015fe Yuvam Kre\u015f ve Et\u00fct Merkezi ile Bright Moonlight Preschool\u2019un \u00f6\u011frencileri ve sorumlu \u00f6\u011fretmenleri kat\u0131ld\u0131. YD\u00dc \u0130leti\u015fim Fak\u00fcltesi Dekan\u0131 Prof. Dr. Fevzi [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/haberkuzey.com\/index.php\/2025\/06\/24\/engelsiz-sinema-salonu-ve-aktivite-merkezinde-animasyon-film-gosterimi-yapildi\/\" \/>\n<meta property=\"og:site_name\" content=\"Haber Kuzey\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-24T07:34:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/brtk.net\/wp-content\/uploads\/2025\/06\/24\/ENGELSIZ-SINEMA-SALONU1.jpeg?ver=7807606dfece457c37f15d0129218301\" \/>\n<meta name=\"author\" content=\"haberkuzey\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Yazan:\" \/>\n\t<meta name=\"twitter:data1\" content=\"haberkuzey\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tahmini okuma s\u00fcresi\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 dakika\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/haberkuzey.com\\\/index.php\\\/2025\\\/06\\\/24\\\/engelsiz-sinema-salonu-ve-aktivite-merkezinde-animasyon-film-gosterimi-yapildi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/haberkuzey.com\\\/index.php\\\/2025\\\/06\\\/24\\\/engelsiz-sinema-salonu-ve-aktivite-merkezinde-animasyon-film-gosterimi-yapildi\\\/\"},\"author\":{\"name\":\"haberkuzey\",\"@id\":\"https:\\\/\\\/haberkuzey.com\\\/#\\\/schema\\\/person\\\/3372109ec735f9333f4fa47ebb9605ca\"},\"headline\":\"Engelsiz Sinema Salonu ve Aktivite Merkezi\u2019nde animasyon film g\u00f6sterimi yap\u0131ld\u0131\",\"datePublished\":\"2025-06-24T07:34:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/haberkuzey.com\\\/index.php\\\/2025\\\/06\\\/24\\\/engelsiz-sinema-salonu-ve-aktivite-merkezinde-animasyon-film-gosterimi-yapildi\\\/\"},\"wordCount\":142,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/haberkuzey.com\\\/index.php\\\/2025\\\/06\\\/24\\\/engelsiz-sinema-salonu-ve-aktivite-merkezinde-animasyon-film-gosterimi-yapildi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/haberkuzey.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/ENGELSIZ-SINEMA-SALONU1.jpeg\",\"articleSection\":[\"K\u0131br\u0131s\"],\"inLanguage\":\"tr\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/haberkuzey.com\\\/index.php\\\/2025\\\/06\\\/24\\\/engelsiz-sinema-salonu-ve-aktivite-merkezinde-animasyon-film-gosterimi-yapildi\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/haberkuzey.com\\\/index.php\\\/2025\\\/06\\\/24\\\/engelsiz-sinema-salonu-ve-aktivite-merkezinde-animasyon-film-gosterimi-yapildi\\\/\",\"url\":\"https:\\\/\\\/haberkuzey.com\\\/index.php\\\/2025\\\/06\\\/24\\\/engelsiz-sinema-salonu-ve-aktivite-merkezinde-animasyon-film-gosterimi-yapildi\\\/\",\"name\":\"Engelsiz Sinema Salonu ve Aktivite Merkezi\u2019nde animasyon film g\u00f6sterimi yap\u0131ld\u0131 - Haber Kuzey\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/haberkuzey.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/haberkuzey.com\\\/index.php\\\/2025\\\/06\\\/24\\\/engelsiz-sinema-salonu-ve-aktivite-merkezinde-animasyon-film-gosterimi-yapildi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/haberkuzey.com\\\/index.php\\\/2025\\\/06\\\/24\\\/engelsiz-sinema-salonu-ve-aktivite-merkezinde-animasyon-film-gosterimi-yapildi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/haberkuzey.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/ENGELSIZ-SINEMA-SALONU1.jpeg\",\"datePublished\":\"2025-06-24T07:34:39+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/haberkuzey.com\\\/#\\\/schema\\\/person\\\/3372109ec735f9333f4fa47ebb9605ca\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/haberkuzey.com\\\/index.php\\\/2025\\\/06\\\/24\\\/engelsiz-sinema-salonu-ve-aktivite-merkezinde-animasyon-film-gosterimi-yapildi\\\/#breadcrumb\"},\"inLanguage\":\"tr\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/haberkuzey.com\\\/index.php\\\/2025\\\/06\\\/24\\\/engelsiz-sinema-salonu-ve-aktivite-merkezinde-animasyon-film-gosterimi-yapildi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"tr\",\"@id\":\"https:\\\/\\\/haberkuzey.com\\\/index.php\\\/2025\\\/06\\\/24\\\/engelsiz-sinema-salonu-ve-aktivite-merkezinde-animasyon-film-gosterimi-yapildi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/haberkuzey.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/ENGELSIZ-SINEMA-SALONU1.jpeg\",\"contentUrl\":\"https:\\\/\\\/haberkuzey.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/ENGELSIZ-SINEMA-SALONU1.jpeg\",\"width\":929,\"height\":408},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/haberkuzey.com\\\/index.php\\\/2025\\\/06\\\/24\\\/engelsiz-sinema-salonu-ve-aktivite-merkezinde-animasyon-film-gosterimi-yapildi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Anasayfa\",\"item\":\"https:\\\/\\\/haberkuzey.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Engelsiz Sinema Salonu ve Aktivite Merkezi\u2019nde animasyon film g\u00f6sterimi yap\u0131ld\u0131\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/haberkuzey.com\\\/#website\",\"url\":\"https:\\\/\\\/haberkuzey.com\\\/\",\"name\":\"Haber Kuzey\",\"description\":\"Do\u011fru Haberin Adresi\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/haberkuzey.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"tr\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/haberkuzey.com\\\/#\\\/schema\\\/person\\\/3372109ec735f9333f4fa47ebb9605ca\",\"name\":\"haberkuzey\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"tr\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f5fc875574b1575324358c3b9e6a32b8227aa5b74f3fa22e3cadb63e26fcc39c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f5fc875574b1575324358c3b9e6a32b8227aa5b74f3fa22e3cadb63e26fcc39c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f5fc875574b1575324358c3b9e6a32b8227aa5b74f3fa22e3cadb63e26fcc39c?s=96&d=mm&r=g\",\"caption\":\"haberkuzey\"},\"sameAs\":[\"https:\\\/\\\/haberkuzey.com\"],\"url\":\"https:\\\/\\\/haberkuzey.com\\\/index.php\\\/author\\\/haberkuzey\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Engelsiz Sinema Salonu ve Aktivite Merkezi\u2019nde animasyon film g\u00f6sterimi yap\u0131ld\u0131 - Haber Kuzey","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/haberkuzey.com\/index.php\/2025\/06\/24\/engelsiz-sinema-salonu-ve-aktivite-merkezinde-animasyon-film-gosterimi-yapildi\/","og_locale":"tr_TR","og_type":"article","og_title":"Engelsiz Sinema Salonu ve Aktivite Merkezi\u2019nde animasyon film g\u00f6sterimi yap\u0131ld\u0131 - Haber Kuzey","og_description":"Yak\u0131n Do\u011fu \u00dcniversitesi (YD\u00dc) ve Telsim i\u015f birli\u011finde yenilenerek kapasitesi art\u0131r\u0131lan Engelsiz Sinema Salonu ve Aktivite Merkezi\u2019nde \u00e7ocuklara y\u00f6nelik animasyon film g\u00f6sterimi yap\u0131ld\u0131.\u00a0 Telsim\u2019den yap\u0131lan a\u00e7\u0131klamaya g\u00f6re, YD\u00dc \u0130leti\u015fim Fak\u00fcltesi\u2019nde bulunan merkezdeki etkinli\u011fe Ne\u015fe Yuvam Kre\u015f ve Et\u00fct Merkezi ile Bright Moonlight Preschool\u2019un \u00f6\u011frencileri ve sorumlu \u00f6\u011fretmenleri kat\u0131ld\u0131. YD\u00dc \u0130leti\u015fim Fak\u00fcltesi Dekan\u0131 Prof. Dr. Fevzi [&hellip;]","og_url":"https:\/\/haberkuzey.com\/index.php\/2025\/06\/24\/engelsiz-sinema-salonu-ve-aktivite-merkezinde-animasyon-film-gosterimi-yapildi\/","og_site_name":"Haber Kuzey","article_published_time":"2025-06-24T07:34:39+00:00","og_image":[{"url":"https:\/\/brtk.net\/wp-content\/uploads\/2025\/06\/24\/ENGELSIZ-SINEMA-SALONU1.jpeg?ver=7807606dfece457c37f15d0129218301","type":"","width":"","height":""}],"author":"haberkuzey","twitter_card":"summary_large_image","twitter_misc":{"Yazan:":"haberkuzey","Tahmini okuma s\u00fcresi":"1 dakika"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/haberkuzey.com\/index.php\/2025\/06\/24\/engelsiz-sinema-salonu-ve-aktivite-merkezinde-animasyon-film-gosterimi-yapildi\/#article","isPartOf":{"@id":"https:\/\/haberkuzey.com\/index.php\/2025\/06\/24\/engelsiz-sinema-salonu-ve-aktivite-merkezinde-animasyon-film-gosterimi-yapildi\/"},"author":{"name":"haberkuzey","@id":"https:\/\/haberkuzey.com\/#\/schema\/person\/3372109ec735f9333f4fa47ebb9605ca"},"headline":"Engelsiz Sinema Salonu ve Aktivite Merkezi\u2019nde animasyon film g\u00f6sterimi yap\u0131ld\u0131","datePublished":"2025-06-24T07:34:39+00:00","mainEntityOfPage":{"@id":"https:\/\/haberkuzey.com\/index.php\/2025\/06\/24\/engelsiz-sinema-salonu-ve-aktivite-merkezinde-animasyon-film-gosterimi-yapildi\/"},"wordCount":142,"commentCount":0,"image":{"@id":"https:\/\/haberkuzey.com\/index.php\/2025\/06\/24\/engelsiz-sinema-salonu-ve-aktivite-merkezinde-animasyon-film-gosterimi-yapildi\/#primaryimage"},"thumbnailUrl":"https:\/\/haberkuzey.com\/wp-content\/uploads\/2025\/06\/ENGELSIZ-SINEMA-SALONU1.jpeg","articleSection":["K\u0131br\u0131s"],"inLanguage":"tr","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/haberkuzey.com\/index.php\/2025\/06\/24\/engelsiz-sinema-salonu-ve-aktivite-merkezinde-animasyon-film-gosterimi-yapildi\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/haberkuzey.com\/index.php\/2025\/06\/24\/engelsiz-sinema-salonu-ve-aktivite-merkezinde-animasyon-film-gosterimi-yapildi\/","url":"https:\/\/haberkuzey.com\/index.php\/2025\/06\/24\/engelsiz-sinema-salonu-ve-aktivite-merkezinde-animasyon-film-gosterimi-yapildi\/","name":"Engelsiz Sinema Salonu ve Aktivite Merkezi\u2019nde animasyon film g\u00f6sterimi yap\u0131ld\u0131 - Haber Kuzey","isPartOf":{"@id":"https:\/\/haberkuzey.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/haberkuzey.com\/index.php\/2025\/06\/24\/engelsiz-sinema-salonu-ve-aktivite-merkezinde-animasyon-film-gosterimi-yapildi\/#primaryimage"},"image":{"@id":"https:\/\/haberkuzey.com\/index.php\/2025\/06\/24\/engelsiz-sinema-salonu-ve-aktivite-merkezinde-animasyon-film-gosterimi-yapildi\/#primaryimage"},"thumbnailUrl":"https:\/\/haberkuzey.com\/wp-content\/uploads\/2025\/06\/ENGELSIZ-SINEMA-SALONU1.jpeg","datePublished":"2025-06-24T07:34:39+00:00","author":{"@id":"https:\/\/haberkuzey.com\/#\/schema\/person\/3372109ec735f9333f4fa47ebb9605ca"},"breadcrumb":{"@id":"https:\/\/haberkuzey.com\/index.php\/2025\/06\/24\/engelsiz-sinema-salonu-ve-aktivite-merkezinde-animasyon-film-gosterimi-yapildi\/#breadcrumb"},"inLanguage":"tr","potentialAction":[{"@type":"ReadAction","target":["https:\/\/haberkuzey.com\/index.php\/2025\/06\/24\/engelsiz-sinema-salonu-ve-aktivite-merkezinde-animasyon-film-gosterimi-yapildi\/"]}]},{"@type":"ImageObject","inLanguage":"tr","@id":"https:\/\/haberkuzey.com\/index.php\/2025\/06\/24\/engelsiz-sinema-salonu-ve-aktivite-merkezinde-animasyon-film-gosterimi-yapildi\/#primaryimage","url":"https:\/\/haberkuzey.com\/wp-content\/uploads\/2025\/06\/ENGELSIZ-SINEMA-SALONU1.jpeg","contentUrl":"https:\/\/haberkuzey.com\/wp-content\/uploads\/2025\/06\/ENGELSIZ-SINEMA-SALONU1.jpeg","width":929,"height":408},{"@type":"BreadcrumbList","@id":"https:\/\/haberkuzey.com\/index.php\/2025\/06\/24\/engelsiz-sinema-salonu-ve-aktivite-merkezinde-animasyon-film-gosterimi-yapildi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Anasayfa","item":"https:\/\/haberkuzey.com\/"},{"@type":"ListItem","position":2,"name":"Engelsiz Sinema Salonu ve Aktivite Merkezi\u2019nde animasyon film g\u00f6sterimi yap\u0131ld\u0131"}]},{"@type":"WebSite","@id":"https:\/\/haberkuzey.com\/#website","url":"https:\/\/haberkuzey.com\/","name":"Haber Kuzey","description":"Do\u011fru Haberin Adresi","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/haberkuzey.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"tr"},{"@type":"Person","@id":"https:\/\/haberkuzey.com\/#\/schema\/person\/3372109ec735f9333f4fa47ebb9605ca","name":"haberkuzey","image":{"@type":"ImageObject","inLanguage":"tr","@id":"https:\/\/secure.gravatar.com\/avatar\/f5fc875574b1575324358c3b9e6a32b8227aa5b74f3fa22e3cadb63e26fcc39c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f5fc875574b1575324358c3b9e6a32b8227aa5b74f3fa22e3cadb63e26fcc39c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f5fc875574b1575324358c3b9e6a32b8227aa5b74f3fa22e3cadb63e26fcc39c?s=96&d=mm&r=g","caption":"haberkuzey"},"sameAs":["https:\/\/haberkuzey.com"],"url":"https:\/\/haberkuzey.com\/index.php\/author\/haberkuzey\/"}]}},"_links":{"self":[{"href":"https:\/\/haberkuzey.com\/index.php\/wp-json\/wp\/v2\/posts\/26470","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/haberkuzey.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/haberkuzey.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/haberkuzey.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/haberkuzey.com\/index.php\/wp-json\/wp\/v2\/comments?post=26470"}],"version-history":[{"count":0,"href":"https:\/\/haberkuzey.com\/index.php\/wp-json\/wp\/v2\/posts\/26470\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/haberkuzey.com\/index.php\/wp-json\/wp\/v2\/media\/26471"}],"wp:attachment":[{"href":"https:\/\/haberkuzey.com\/index.php\/wp-json\/wp\/v2\/media?parent=26470"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/haberkuzey.com\/index.php\/wp-json\/wp\/v2\/categories?post=26470"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/haberkuzey.com\/index.php\/wp-json\/wp\/v2\/tags?post=26470"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}